{"id":23359,"date":"2014-05-27T00:00:00","date_gmt":"2014-05-27T04:00:00","guid":{"rendered":"http:\/\/ceric.org\/2014\/05\/overcoming-barriers-for-criminalized-clients\/"},"modified":"2018-06-25T10:16:14","modified_gmt":"2018-06-25T14:16:14","slug":"overcoming-barriers-for-criminalized-clients","status":"publish","type":"post","link":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/","title":{"rendered":"Surmonter les obstacles pour les clients criminalis\u00e9s"},"content":{"rendered":"<p><em>Par Ritchy Dub\u00e9<\/em><\/p>\n<h6 align=\"center\">Les anciens d\u00e9linquants qui tentent de r\u00e9int\u00e9grer la soci\u00e9t\u00e9 font face \u00e0 une foule de pr\u00e9jug\u00e9s, y compris de la part de ceux qui essaient de les aider<\/h6>\n<p><!--more--><\/p>\n<p>Je suis un auteur dont les \u00e9crits ont \u00e9t\u00e9 publi\u00e9s \u00e0 l\u2019\u00e9chelle nationale (quelle affaire!), un th\u00e9rapeute en toxicomanie agr\u00e9\u00e9, le fondateur et directeur g\u00e9n\u00e9ral d\u2019un organisme pour la pr\u00e9vention de l\u2019abus de drogues et le pr\u00e9sident-fondateur d\u2019une agence de recrutement qui trouve des emplois aux anciens d\u00e9tenus. Au plus fort de mes activit\u00e9s, j\u2019ai eu 75\u00a0employ\u00e9s. De ce nombre, de 50 \u00e0 70\u00a0% \u00e9taient eux-m\u00eames d\u2019anciens d\u00e9tenus.<\/p>\n<p>Les universit\u00e9s Laurentian, McMaster et Simon Fraser m\u2019ont gentiment d\u00e9cern\u00e9 des dipl\u00f4mes, tandis que le coll\u00e8ge Cambrian m\u2019a donn\u00e9 une formation ad\u00e9quate en administration des affaires. Ah oui, j\u2019ai aussi \u00e9t\u00e9 incarc\u00e9r\u00e9 pendant huit ans dans des p\u00e9nitenciers canadiens o\u00f9 j\u2019ai appris \u00e0 me m\u00ealer de mes affaires, \u00e0 me sortir de situations dangereuses et o\u00f9 j\u2019ai lu de nombreux classiques, mais je n\u2019ai re\u00e7u aucun certificat pour ces exploits.<\/p>\n<p>Vous pouvez imaginer combien peu nombreux sont les gens ou les organismes pr\u00eats \u00e0 aider les personnes stigmatis\u00e9es comme moi. J\u2019ai d\u00e9couvert avec tristesse que beaucoup de conseillers en emploi sont r\u00e9ticents \u00e0 nous venir en aide. Ils ont leurs raisons et je vais les aborder ici, mais avant tout, je tiens \u00e0 vous dire que, comme je n\u2019aime pas recevoir de conseils non sollicit\u00e9s, je n\u2019en donnerai pas non plus. Je veux partager mon exp\u00e9rience de conseiller en emploi ayant travaill\u00e9 avec des personnes criminalis\u00e9es, et de consommateur de services d\u2019emploi en tant que client criminalis\u00e9 et stigmatis\u00e9. J\u2019ai pens\u00e9 que cette double perspective pourrait \u00eatre utile.<\/p>\n<p>En tant que consommateurs, les personnes stigmatis\u00e9es cherchent sans cesse un r\u00e9pit, du soutien, des conseils, de la compr\u00e9hension, de l\u2019acceptation et un emploi. Mais souvent, elles se retrouvent \u00e9cras\u00e9es, humili\u00e9es, d\u00e9sesp\u00e9r\u00e9es et \u00e0 la d\u00e9rive. Certains de ces hommes et femmes ont \u00e9t\u00e9 des membres productifs de la soci\u00e9t\u00e9 pendant plusieurs ann\u00e9es, mais la chance ne leur sourit pas. Nous, les anciens d\u00e9tenus, ne voulons pas \u00eatre f\u00e9licit\u00e9s pour \u00eatre entr\u00e9s dans le droit chemin, mais nous n\u2019avons certainement pas besoin d\u2019obstacles suppl\u00e9mentaires. Nous voulons simplement travailler, nourrir notre famille, \u00e9conomiser et peut-\u00eatre m\u00eame voyager.<\/p>\n<p>Donc, si nous pr\u00e9sumons que nous, les conseillers en emploi, voulons r\u00e9duire et supprimer certains de ces obstacles, que pouvons-nous faire pour rendre notre milieu de travail plus inclusif afin d\u2019aider les anciens d\u00e9linquants \u00e0 trouver un emploi et m\u00eame de les engager comme conseillers en emploi? Je crois qu\u2019il est possible de faire quelque chose, mais qu\u2019il faut la bonne attitude. Ce changement dans la fa\u00e7on de penser devra se faire des deux c\u00f4t\u00e9s\u00a0: l\u2019ancien d\u00e9linquant devra prouver qu\u2019il participe \u00e0 des activit\u00e9s sociales positives et le conseiller devra t\u00e9moigner d\u2019un d\u00e9sir sinc\u00e8re de lui venir en aide. Cette proposition est fond\u00e9e sur la conviction toute simple que le conseiller professionnel a la volont\u00e9, l\u2019intelligence et le d\u00e9sir de s\u2019am\u00e9liorer. Cela exige de l\u2019int\u00e9grit\u00e9, de l\u2019exp\u00e9rience et du professionnalisme.<\/p>\n<p>Nous, les gens pr\u00e9tendument inform\u00e9s et \u00e9duqu\u00e9s, faisons parfois preuve de cynisme et d\u2019\u00e9troitesse d\u2019esprit. Je m\u2019inclus dans cette description. Moi aussi, j\u2019ai de la difficult\u00e9 \u00e0 faire confiance. Moi aussi, je dois am\u00e9liorer mon attitude. Tr\u00e8s souvent, nous sommes craintifs et intol\u00e9rants. Parfois, nous n\u2019aimons tout simplement pas les anciens d\u00e9tenus. La plupart d\u2019entre nous sommes r\u00e9ticents \u00e0 aider les anciens d\u00e9linquants pour une ou plusieurs des raisons suivantes :<\/p>\n<ul>\n<li>Nous, les gens irr\u00e9prochables (si de telles personnes existent; pas moi en tout cas, j\u2019ai d\u00e9j\u00e0 avou\u00e9) n\u2019avons jamais eu \u00e0 faire face \u00e0 l\u2019adversit\u00e9 et n\u2019avons aucune exp\u00e9rience du processus de transformation. Par cons\u00e9quent, nous ne faisons pas confiance;<\/li>\n<li>Nous avons une opinion n\u00e9gative des personnes qui ont d\u00e9j\u00e0 \u00e9t\u00e9 antisociales et particip\u00e9 \u00e0 des activit\u00e9s criminelles;<\/li>\n<li>Nous avons peur;<\/li>\n<li>Nous avons peut-\u00eatre \u00e9t\u00e9 des victimes;<\/li>\n<li>Nous ne voulons pas couper les ponts avec nos employeurs;<\/li>\n<li>Nous ne voulons pas associer notre organisme \u00e0 d\u2019anciens criminels;<\/li>\n<li>Nous ne voulons pas perdre de temps avec un candidat moins int\u00e9ressant alors que nous pourrions aider un candidat irr\u00e9prochable.<\/li>\n<\/ul>\n<p>Pas de souci\u00a0: nous, les anciens durs, comprenons parfaitement, car nous avons les m\u00eames sentiments les uns \u00e0 l\u2019\u00e9gard des autres, jusqu\u2019\u00e0 ce que nous apprenions \u00e0 nous conna\u00eetre. Cependant, j\u2019ai pourvu beaucoup de postes dans le domaine de la construction, et ni moi ni l\u2019employeur n\u2019avons jamais \u00e9t\u00e9 vol\u00e9s ou bless\u00e9s. Soit les hommes se pr\u00e9sentaient au boulot et travaillaient dur, soit ils ne se pr\u00e9sentaient pas. Ce n\u2019est pas diff\u00e9rent des autres gens que j\u2019ai plac\u00e9 en emploi.<\/p>\n<p>Dans le cas de placements plus \u00ab d\u00e9licats \u00bb, cependant, la diligence est de mise, et c\u2019est alors qu\u2019apprendre \u00e0 se conna\u00eetre devient profitable, alors l\u2019une de mes strat\u00e9gies consiste \u00e0 travailler quelque temps avec la personne pour apprendre \u00e0 se conna\u00eetre mutuellement. Il ne faut pas beaucoup de temps pour comprendre qu\u2019une personne a des intentions s\u00e9rieuses. Elle a fait des efforts pour changer, est sortie de prison depuis quelque temps, se pr\u00e9sente \u00e0 ses rendez-vous bien mise et sobre, porte des v\u00eatements convenables, remplit ses obligations, ex\u00e9cute ses t\u00e2ches et communique honn\u00eatement, respectueusement et calmement. Elle n\u2019h\u00e9site pas \u00e0 me fournir des recommandations \u00e9crites et \u00e0 discuter de son ancienne vie. Tout comme moi, ces personnes ne voient aucun inconv\u00e9nient \u00e0 divulguer certains renseignements une fois que le respect et la compr\u00e9hension sont install\u00e9s.<\/p>\n<p>En tant que conseiller professionnel, il me suffit de respecter leur vie priv\u00e9e et de pr\u00e9server leur dignit\u00e9. Pour ce faire, je dois faire un exercice d\u2019introspection et me poser des questions tr\u00e8s pointues comme\u00a0:<\/p>\n<ol>\n<li>\u00c0 quel point est-il important que je sache?<\/li>\n<li>Est-ce que j\u2019enfreins des lois en posant ces questions?<\/li>\n<li>Est-ce pertinent pour l\u2019emploi postul\u00e9?<\/li>\n<li>Quelles sont les raisons pour lesquelles je pose ces questions?<\/li>\n<\/ol>\n<p>Ces questions et d\u2019autres m\u2019aident \u00e0 me rep\u00e9rer dans la relation et \u00e0 engager le dialogue. Il est \u00e9galement important que je sois un bon mod\u00e8le en ne perdant jamais de vue la diff\u00e9rence de pouvoir entre moi et l\u2019autre. Surtout, je dois me rappeler mon r\u00f4le essentiel de gardien du lieu de travail. Ces personnes comptent sur moi pour transformer leur vie en leur trouvant un emploi qui les aidera \u00e0 redonner un sens \u00e0 leur existence, \u00e0 \u00eatre accept\u00e9es et \u00e0 avoir un sentiment de s\u00e9curit\u00e9. C\u2019est une \u00e9norme responsabilit\u00e9.<\/p>\n<p>En fin de compte, travailler avec des populations criminalis\u00e9es consiste davantage \u00e0 d\u00e9finir le genre de personne et de professionnel qu\u2019on veut \u00eatre qu\u2019\u00e0 prot\u00e9ger les autres. Si nous agissons avec diligence, sommes honn\u00eates avec nous-m\u00eames, faisons attention \u00e0 la relation et nous effor\u00e7ons de la faire fructifier, notre travail sera grandement facilit\u00e9 et, par cons\u00e9quent, la d\u00e9cision de venir en aide ou non \u00e0 la personne peut \u00eatre prise avec confiance et certitude. Nul besoin de jouer \u00e0 des charades, de suivre la personne \u00e0 la trace ni de trouver des excuses.<\/p>\n<p>Pour r\u00e9sumer, le changement va dans les deux sens. J\u2019ai d\u00fb changer, grandir en sagesse, m\u00fbrir et me responsabiliser pour devenir conseiller professionnel, et j\u2019ai d\u00fb changer pour devenir un conseiller professionnel efficace et empathique qui agit de mani\u00e8re \u00e9thique et avec int\u00e9grit\u00e9. Je suis tr\u00e8s heureux d\u2019avoir r\u00e9ussi \u00e0 surmonter ces obstacles, parce que vivre moi-m\u00eame le processus de transformation et le voir s\u2019enraciner chez les autres est l\u2019aspect le plus enrichissant de ma vie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ritchy Dub\u00e9<\/strong>\u00a0<em>est un gars ordinaire qui veut vivre une existence normale. Il est n\u00e9 et a grandi \u00e0 Sudbury, ON et souhaite rendre la vie plus \u00e9quitable pour tous. Ritchy vous invite \u00e0 lui transmettre vos commentaires \u00e0\u00a0<a href=\"mailto:sendakite@gmail.com\" target=\"_blank\" rel=\"noopener\">sendakite@gmail.com<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Ritchy Dub\u00e9 Les anciens d\u00e9linquants qui tentent de r\u00e9int\u00e9grer la soci\u00e9t\u00e9 font face \u00e0 une foule de pr\u00e9jug\u00e9s, y compris de la part de ceux<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","h5ap_radio_sources":[],"page_builder":"","footnotes":""},"categories":[467,473,623],"tags":[],"class_list":["post-23359","post","type-post","status-publish","format-standard","hentry","category-careering-fr","category-printemps-ete-2014","category-sp14-fr-article-de-fond"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Surmonter les obstacles pour les clients criminalis\u00e9s - CERIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surmonter les obstacles pour les clients criminalis\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Par Ritchy Dub\u00e9 Les anciens d\u00e9linquants qui tentent de r\u00e9int\u00e9grer la soci\u00e9t\u00e9 font face \u00e0 une foule de pr\u00e9jug\u00e9s, y compris de la part de ceux [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/\" \/>\n<meta property=\"og:site_name\" content=\"CERIC\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-27T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-25T14:16:14+00:00\" \/>\n<meta name=\"author\" content=\"Norman Valdez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rachel@ceric.ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman Valdez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/\"},\"author\":{\"name\":\"Norman Valdez\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\"},\"headline\":\"Surmonter les obstacles pour les clients criminalis\u00e9s\",\"datePublished\":\"2014-05-27T04:00:00+00:00\",\"dateModified\":\"2018-06-25T14:16:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/\"},\"wordCount\":1426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"articleSection\":[\"Careering\",\"Printemps\\\/\u00e9t\u00e9 2014\",\"SP14 \u2013 FR \u2013 Article de fond\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/\",\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/\",\"name\":\"Surmonter les obstacles pour les clients criminalis\u00e9s - CERIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\"},\"datePublished\":\"2014-05-27T04:00:00+00:00\",\"dateModified\":\"2018-06-25T14:16:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2014\\\/05\\\/overcoming-barriers-for-criminalized-clients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/ceric-homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Surmonter les obstacles pour les clients criminalis\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"name\":\"CERIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceric.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\",\"name\":\"CERIC\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CERIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\",\"name\":\"Norman Valdez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"caption\":\"Norman Valdez\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/rachel@ceric.ca\"],\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/author\\\/norman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Surmonter les obstacles pour les clients criminalis\u00e9s - CERIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/","og_locale":"fr_FR","og_type":"article","og_title":"Surmonter les obstacles pour les clients criminalis\u00e9s","og_description":"Par Ritchy Dub\u00e9 Les anciens d\u00e9linquants qui tentent de r\u00e9int\u00e9grer la soci\u00e9t\u00e9 font face \u00e0 une foule de pr\u00e9jug\u00e9s, y compris de la part de ceux [\u2026]","og_url":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/","og_site_name":"CERIC","article_published_time":"2014-05-27T04:00:00+00:00","article_modified_time":"2018-06-25T14:16:14+00:00","author":"Norman Valdez","twitter_card":"summary_large_image","twitter_creator":"@rachel@ceric.ca","twitter_misc":{"\u00c9crit par":"Norman Valdez","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/#article","isPartOf":{"@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/"},"author":{"name":"Norman Valdez","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2"},"headline":"Surmonter les obstacles pour les clients criminalis\u00e9s","datePublished":"2014-05-27T04:00:00+00:00","dateModified":"2018-06-25T14:16:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/"},"wordCount":1426,"commentCount":0,"publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"articleSection":["Careering","Printemps\/\u00e9t\u00e9 2014","SP14 \u2013 FR \u2013 Article de fond"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/","url":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/","name":"Surmonter les obstacles pour les clients criminalis\u00e9s - CERIC","isPartOf":{"@id":"https:\/\/ceric.ca\/#website"},"datePublished":"2014-05-27T04:00:00+00:00","dateModified":"2018-06-25T14:16:14+00:00","breadcrumb":{"@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ceric.ca\/fr\/2014\/05\/overcoming-barriers-for-criminalized-clients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceric.ca\/fr\/ceric-homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Surmonter les obstacles pour les clients criminalis\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/ceric.ca\/#website","url":"https:\/\/ceric.ca\/","name":"CERIC","description":"","publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceric.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ceric.ca\/#organization","name":"CERIC","url":"https:\/\/ceric.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CERIC"},"image":{"@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2","name":"Norman Valdez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","caption":"Norman Valdez"},"sameAs":["https:\/\/x.com\/rachel@ceric.ca"],"url":"https:\/\/ceric.ca\/fr\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/23359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/comments?post=23359"}],"version-history":[{"count":0,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/23359\/revisions"}],"wp:attachment":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media?parent=23359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/categories?post=23359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/tags?post=23359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}