{"id":23499,"date":"2017-10-18T00:00:00","date_gmt":"2017-10-18T04:00:00","guid":{"rendered":"http:\/\/ceric.org\/2017\/10\/hope-based-interventions-with-unemployed-clients\/"},"modified":"2018-06-25T10:11:05","modified_gmt":"2018-06-25T14:11:05","slug":"hope-based-interventions-with-unemployed-clients","status":"publish","type":"post","link":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/","title":{"rendered":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi"},"content":{"rendered":"<p><em>Par Norman Amundson, Tannis Goddard, Spencer Niles et Hyung Joon Yoon<\/em><\/p>\n<h6 style=\"text-align: center;\">Les rencontres en personne et les exercices en ligne permettent aux chercheurs d\u2019emploi de conserver un sentiment d\u2019espoir alors qu\u2019il est tr\u00e8s facile de c\u00e9der aux \u00e9motions n\u00e9gatives<\/h6>\n<p><!--more--><\/p>\n<div id=\"post-content\">\n<p>Il existe une litt\u00e9rature consid\u00e9rable sur l\u2019incidence n\u00e9gative du ch\u00f4mage. La recherche souligne l\u2019incidence du ch\u00f4mage sur les relations, l\u2019estime de soi, les buts de vie et le mieux-\u00eatre physique. Le ch\u00f4mage entra\u00eene souvent des sentiments d\u2019isolement, de d\u00e9pression, de col\u00e8re, de manque d\u2019estime de soi et de d\u00e9sespoir. L\u2019un des d\u00e9fis des clients sans emploi est de conserver un sentiment d\u2019espoir et de contr\u00f4le dans un contexte o\u00f9 il est tr\u00e8s facile de c\u00e9der \u00e0 des pens\u00e9es et des \u00e9motions n\u00e9gatives. La recherche d\u2019emploi fait appel \u00e0 de multiples comp\u00e9tences et actions; elle est plus facile \u00e0 mener si elle prend pour point de d\u00e9part un espoir ouvert sur l\u2019action.<\/p>\n<p>Spencer Niles, Norman Amundson et Hyung Joon Yoon ont mis au point un mod\u00e8le de d\u00e9veloppement de carri\u00e8re ax\u00e9 sur l\u2019action et l\u2019espoir (Niles, Amundson et Neault, 2011). Ce mod\u00e8le est con\u00e7u \u00e0 l\u2019image d\u2019un moulinet dont l\u2019axe est l\u2019espoir. Les pales qui l\u2019entourent repr\u00e9sentent les diff\u00e9rentes \u00e9tapes du processus d\u00e9veloppement de carri\u00e8re :<\/p>\n<ul>\n<li><strong>La r\u00e9flexion sur soi<\/strong>\u00a0\u2013 songer aux aspects qui comptent le plus pour soi et r\u00e9pondre aux grandes questions sur ce qu\u2019on souhaite accomplir dans la vie et sur les comp\u00e9tences qu\u2019on poss\u00e8de et qu\u2019on souhaite perfectionner;<\/li>\n<li><strong>L\u2019autocompr\u00e9hension<\/strong>\u00a0\u2013 d\u00e9terminer ses valeurs, ses int\u00e9r\u00eats, ses comp\u00e9tences et son style personnel;<\/li>\n<li><strong>La visualisation<\/strong>\u00a0\u2013 envisager les possibilit\u00e9s \u00e0 plus long terme;<\/li>\n<li><strong>L\u2019\u00e9tablissement d\u2019objectifs et la planification<\/strong>\u00a0\u2013 \u00e9laborer une strat\u00e9gie pour atteindre des objectifs significatifs \u00e0 court et \u00e0 long terme;<\/li>\n<li><strong>La mise en \u0153uvre et l\u2019adaptation<\/strong>\u00a0\u2013 passer \u00e0 l\u2019action et apporter des modifications en cours de route.<\/li>\n<\/ul>\n<p>Des facteurs environnementaux entourent le moulinet (comme le vent) et contribuent \u00e0 cr\u00e9er un mouvement. Ce mod\u00e8le permet de conceptualiser plus facilement le processus de d\u00e9veloppement de carri\u00e8re, ainsi que de cerner et de d\u00e9velopper des interventions adapt\u00e9es aux comp\u00e9tences professionnelles.<\/p>\n<p>Ce projet de recherche, financ\u00e9 par le CERIC, a mis en pratique le mod\u00e8le de d\u00e9veloppement de carri\u00e8re ax\u00e9 sur l\u2019action et l\u2019espoir dans deux diff\u00e9rents centres d\u2019emploi en Colombie-Britannique. L\u2019accent a \u00e9t\u00e9 mis sur la participation des clients individuels \u00e0 une s\u00e9rie d\u2019interventions ax\u00e9es sur l\u2019espoir, faites en personne ou en ligne.<\/p>\n<p>L\u2019\u00e9tude a repos\u00e9 sur les interventions suivantes :<\/p>\n<ul>\n<li><strong>D\u00e9marche de r\u00e9solution (\u00e9galement appel\u00e9e la \u00ab question miracle \u00bb)<\/strong>\u00a0\u2013 Exercice dans lequel les clients commencent par rep\u00e9rer la situation probl\u00e9matique. Ils pensent ensuite \u00e0 la solution souhait\u00e9e et se d\u00e9placent physiquement au lieu qui repr\u00e9sente cette solution. De ce point de vue, ils examinent le chemin parcouru et d\u00e9terminent les emb\u00fbches qu\u2019il rec\u00e8le. (Visualisation; \u00e9tablissement d\u2019objectifs et planification)<\/li>\n<li><strong>La carri\u00e8re comme cours d\u2019une rivi\u00e8re<\/strong>\u00a0\u2013 Activit\u00e9 au cours de laquelle les clients sont invit\u00e9s \u00e0 utiliser l\u2019image d\u2019un cours d\u2019eau pour r\u00e9fl\u00e9chir \u00e0 leur avancement professionnel. Il y a des moments o\u00f9 tout se d\u00e9roule parfaitement, sans heurts (cheminement optimal), et d\u2019autres o\u00f9 l\u2019on fait face \u00e0 une stagnation, \u00e0 des remous, voire \u00e0 des chutes. (R\u00e9flexion sur soi)<\/li>\n<li><strong>Cercle du pouvoir<\/strong>\u00a0\u2013 Exercice o\u00f9 les clients racontent des histoires de r\u00e9ussite ou des moments o\u00f9 tout s\u2019est bien d\u00e9roul\u00e9. Leurs int\u00e9r\u00eats, leurs valeurs, leurs aptitudes et leurs comp\u00e9tences font partie de ces histoires, et le conseiller travaille avec les clients pour d\u00e9terminer les points forts de leurs histoires. (Autocompr\u00e9hension)<\/li>\n<li><strong>Deux ou trois chaises<\/strong>\u00a0\u2013 Lorsque les gens prennent des d\u00e9cisions, ils choisissent souvent entre deux options. Chaque option est repr\u00e9sent\u00e9e par une chaise (il peut y avoir plus de deux options), et les clients sont invit\u00e9s \u00e0 s\u2019asseoir sur chaque chaise et \u00e0 d\u00e9crire ce qu\u2019ils ressentent au sujet de ce choix. Une troisi\u00e8me chaise est apport\u00e9e, et les clients ont l\u2019occasion de sortir de leur situation et de consid\u00e9rer de l\u2019ext\u00e9rieur la relation entre les options. Il existe peut-\u00eatre des fa\u00e7ons de rapprocher les chaises, de les empiler ou de les aligner. Ces actions ext\u00e9riorisent le probl\u00e8me et permettent d\u2019imaginer de nouvelles solutions. (\u00c9tablissement d\u2019objectifs et planification)<\/li>\n<li><strong>Se maintenir \u00e0 flot<\/strong>\u00a0\u2013 Le ch\u00f4mage n\u2019est pas le premier probl\u00e8me que les gens connaissent dans leur vie. Il faut mettre ici l\u2019accent sur les autres probl\u00e8mes qui ont \u00e9t\u00e9 r\u00e9solus, en s\u2019int\u00e9ressant aux comp\u00e9tences et aux strat\u00e9gies qui ont \u00e9t\u00e9 utilis\u00e9es pour y parvenir. (Mise en \u0153uvre et adaptation)<\/li>\n<\/ul>\n<p>Outre ces types d\u2019intervention, les clients ont \u00e9t\u00e9 introduits \u00e0 l\u2019outil Hope-Centered Career Inventory (HCCI), une auto\u00e9valuation en 28 questions fond\u00e9e sur le mod\u00e8le de d\u00e9veloppement de carri\u00e8re ax\u00e9 sur l\u2019espoir qui aide les gens \u00e0 \u00e9valuer leurs forces et leurs d\u00e9savantages dans chaque domaine de comp\u00e9tence professionnelle (Niles, Yoon et Amundson, 2010). Enfin, une attention toute particuli\u00e8re a \u00e9t\u00e9 port\u00e9e \u00e0 l\u2019\u00e9tablissement de relations de travail positives entre les conseillers et les clients. Il \u00e9tait essentiel que les clients aient le sentiment qu\u2019ils \u00ab comptaient \u00bb et avaient leur place tout au long de la p\u00e9riode de consultation.<\/p>\n<p>Vous pouvez t\u00e9l\u00e9charger le rapport sur les interventions ax\u00e9es sur l\u2019espoir \u00e0 l\u2019adresse\u00a0<a href=\"\/?p=10675\" target=\"_blank\" rel=\"noopener\">ceric.ca\/fr\/project\/interventions-axees-sur-lespoir<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Le Dr Norman Amundson<\/strong>\u00a0est professeur en psychologie de l\u2019orientation \u00e0 l\u2019Universit\u00e9 de la Colombie-Britannique. Il a \u00e9crit de nombreux articles et ouvrages et a donn\u00e9 de multiples pr\u00e9sentations, ateliers et s\u00e9minaires lors de congr\u00e8s nationaux et internationaux. Il a re\u00e7u plusieurs prix professionnels, dont un doctorat honorifique de l\u2019Universit\u00e9 d\u2019Ume\u00e5 en Su\u00e8de.<\/em><\/p>\n<p><em><strong>Le Dr Spencer Niles<\/strong>\u00a0est doyen et professeur au Coll\u00e8ge William &amp; Mary, aux \u00c9tats-Unis. Il est \u00e9crivain prolifique et a parl\u00e9 \u00e0 de nombreuses conf\u00e9rences nationales et internationales. Il est \u00e9galement ancien pr\u00e9sident de la NCDA.<\/em><\/p>\n<p><em><strong>Le Dr Hyung Joon Yoon<\/strong>\u00a0est actuellement Professeur adjoint de l\u2019\u00e9ducation et du d\u00e9veloppement de la main-d\u2019\u0153uvre \u00e0 l\u2019Universit\u00e9 de Pennsylvanie. Son travail \u00e9rudit est ax\u00e9 sur l\u2019autonomisation des individus et des organisations avec l\u2019agence humaine et l\u2019espoir.<\/em><\/p>\n<p><em><strong>Tannis Goddard<\/strong>\u00a0est pr\u00e9sidente de Training Innovations et son organisation g\u00e8re plusieurs centres de ch\u00f4mage en Colombie-Britannique. Elle termine \u00e9galement son doctorat. Goddard se concentre sur le d\u00e9veloppement de l\u2019intervention en face-\u00e0-face et en ligne.<\/em><\/p>\n<p><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p>Butterfield, L. D., Borgen, W. A., Maglio, A. T. et Amundson, N. E. (2009). \u00ab Using the Enhanced Critical Incident Technique in counselling psychology research \u00bb, Revue canadienne de counseling, 43(4), 265-282. Consult\u00e9 en ligne : cjc.synergiesprairies.ca\/cjc\/index.php\/rcc\/article\/view\/388\/722.<\/p>\n<p>Corbi\u00e8re, M. et Amundson, N. E. (2007). \u00ab Perceptions of the ways of mattering by people with mental illness \u00bb, The Career Development Quarterly, 56(2), 141\u2013149. En ligne :\u00a0<a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/j.2161-0045.2007.tb00026.x\/abstract;jsessionid=7CAA893F3E1F3EB91F5632AABBD7DB9F.f04t03\" target=\"_blank\" rel=\"noopener\">doi.org\/10.1002\/j.2161-0045.2007.tb00026.x<\/a>.<\/p>\n<p>Hirschi, A., Freund, P. A. et Herrmann, A. (2014). \u00ab The Career Engagement Scale : Development and validation of a measure of proactive career behaviors \u00bb, Journal of Career Assessment, 22(4), 575\u2013594. En ligne : doi.org\/10.1177\/1069072713514813.<\/p>\n<p>Holland, J. L., Daiger, D. et Power, P. G. (1980).\u00a0<em>My vocational situation: Description of an experimental diagnostic from for the selection of vocational assistance<\/em>. Palo Alto (CA) : Consulting Psychologists Press.<\/p>\n<p>Niles, S., Amundson, N. et Neault, R. (2011).\u00a0<em>Career\u00a0<\/em>flow :<em>\u00a0A Hope-Centered Approach to Career Development<\/em>. Columbus (OH) : Pearson, Merrill Prentice Hall.<\/p>\n<p>Niles, S. G., Yoon, H. J. et Amundson, N. E. (2010). \u00ab The Hope-Centered Career Inventory \u00bb, auto\u00e9valuation en ligne. Consult\u00e9 sur : mycareerflow.com.<\/p>\n<p>Schwarzer, R. et Jerusalem, M. (1995). \u00ab Generalized Self-Efficacy scale \u00bb, dans J. Weinman, S. Wright et M. Johnston (dir. publ.), Measures in health psychology : A users portfolio. Causal and control beliefs, p. 35-37. Windsor (R.-U.) : NFER-NELSON.<\/p>\n<\/div>\n<div class=\"author-info\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Par Norman Amundson, Tannis Goddard, Spencer Niles et Hyung Joon Yoon Les rencontres en personne et les exercices en ligne permettent aux chercheurs d\u2019emploi de conserver<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","h5ap_radio_sources":[],"page_builder":"","footnotes":""},"categories":[486,467,620],"tags":[],"class_list":["post-23499","post","type-post","status-publish","format-standard","hentry","category-automne-2017","category-careering-fr","category-f17-fr-article-de-fond"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi - CERIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi\" \/>\n<meta property=\"og:description\" content=\"Par Norman Amundson, Tannis Goddard, Spencer Niles et Hyung Joon Yoon Les rencontres en personne et les exercices en ligne permettent aux chercheurs d\u2019emploi de conserver [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/\" \/>\n<meta property=\"og:site_name\" content=\"CERIC\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-18T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-25T14:11:05+00:00\" \/>\n<meta name=\"author\" content=\"Norman Valdez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rachel@ceric.ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman Valdez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/\"},\"author\":{\"name\":\"Norman Valdez\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\"},\"headline\":\"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi\",\"datePublished\":\"2017-10-18T04:00:00+00:00\",\"dateModified\":\"2018-06-25T14:11:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/\"},\"wordCount\":1392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"articleSection\":[\"Automne 2017\",\"Careering\",\"F17 \u2013 FR \u2013 Article de fond\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/\",\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/\",\"name\":\"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi - CERIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\"},\"datePublished\":\"2017-10-18T04:00:00+00:00\",\"dateModified\":\"2018-06-25T14:11:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2017\\\/10\\\/hope-based-interventions-with-unemployed-clients\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/ceric-homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"name\":\"CERIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceric.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\",\"name\":\"CERIC\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CERIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\",\"name\":\"Norman Valdez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"caption\":\"Norman Valdez\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/rachel@ceric.ca\"],\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/author\\\/norman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi - CERIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/","og_locale":"fr_FR","og_type":"article","og_title":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi","og_description":"Par Norman Amundson, Tannis Goddard, Spencer Niles et Hyung Joon Yoon Les rencontres en personne et les exercices en ligne permettent aux chercheurs d\u2019emploi de conserver [\u2026]","og_url":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/","og_site_name":"CERIC","article_published_time":"2017-10-18T04:00:00+00:00","article_modified_time":"2018-06-25T14:11:05+00:00","author":"Norman Valdez","twitter_card":"summary_large_image","twitter_creator":"@rachel@ceric.ca","twitter_misc":{"\u00c9crit par":"Norman Valdez","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/#article","isPartOf":{"@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/"},"author":{"name":"Norman Valdez","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2"},"headline":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi","datePublished":"2017-10-18T04:00:00+00:00","dateModified":"2018-06-25T14:11:05+00:00","mainEntityOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/"},"wordCount":1392,"commentCount":0,"publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"articleSection":["Automne 2017","Careering","F17 \u2013 FR \u2013 Article de fond"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/","url":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/","name":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi - CERIC","isPartOf":{"@id":"https:\/\/ceric.ca\/#website"},"datePublished":"2017-10-18T04:00:00+00:00","dateModified":"2018-06-25T14:11:05+00:00","breadcrumb":{"@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ceric.ca\/fr\/2017\/10\/hope-based-interventions-with-unemployed-clients\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceric.ca\/fr\/ceric-homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Interventions bas\u00e9es sur l\u2019espoir avec les clients sans emploi"}]},{"@type":"WebSite","@id":"https:\/\/ceric.ca\/#website","url":"https:\/\/ceric.ca\/","name":"CERIC","description":"","publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceric.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ceric.ca\/#organization","name":"CERIC","url":"https:\/\/ceric.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CERIC"},"image":{"@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2","name":"Norman Valdez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","caption":"Norman Valdez"},"sameAs":["https:\/\/x.com\/rachel@ceric.ca"],"url":"https:\/\/ceric.ca\/fr\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/23499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/comments?post=23499"}],"version-history":[{"count":0,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/23499\/revisions"}],"wp:attachment":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media?parent=23499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/categories?post=23499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/tags?post=23499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}