{"id":28783,"date":"2012-11-06T16:45:52","date_gmt":"2012-11-06T21:45:52","guid":{"rendered":"http:\/\/ceric.ca\/?p=28783"},"modified":"2018-06-26T16:38:25","modified_gmt":"2018-06-26T20:38:25","slug":"notre-avis-sur-loutil-guide-dorientation-professionnelle","status":"publish","type":"post","link":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/","title":{"rendered":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle"},"content":{"rendered":"<p align=\"left\"><em>par Anne-Marie Blanchet<\/em><\/p>\n<p align=\"left\">\u00c9labor\u00e9 \u00e0 partir des principaux concepts d\u00e9velopp\u00e9s par le Dr. Barbara Moses, auteure \u00e0 succ\u00e8s de nombreux ouvrages, le <em>Guide d\u2019orientation professionnelle<\/em> constitue un nouvel outil interactif en lien avec la carri\u00e8re. Tenir les r\u00eanes de sa vie professionnelle est l\u2019un des principes cl\u00e9s du Guide d\u2019orientation professionnelle. Cet outil fournit l\u2019aide n\u00e9cessaire pour tracer un trajet personnel ainsi que pour surmonter les nombreux d\u00e9fis que comporte la carri\u00e8re. Le <em>Guide d\u2019orientation professionnelle<\/em> permet d\u2019entreprendre des auto\u00e9valuations en r\u00e9pondant \u00e0 une s\u00e9rie de questions. Les r\u00e9ponses sont conserv\u00e9es et permettent de produire des rapports personnels qui fournissent une r\u00e9troaction, des synth\u00e8ses et des recommandations de perfectionnement. Il est important de noter que tous les r\u00e9sultats doivent passer par un processus de r\u00e9flexion. Il faut donc pr\u00e9voir suffisamment de temps pour r\u00e9pondre aux questions ainsi que pour interpr\u00e9ter ses r\u00e9sultats. Dans cet outil, l\u2019utilisateur a la libert\u00e9 de choisir les exercices qu\u2019il d\u00e9sire compl\u00e9ter, car il s\u2019agit de son aventure. L\u2019ensemble des \u00e9valuations et des rapports personnels seront automatiquement int\u00e9gr\u00e9s au Dossier de carri\u00e8re, le r\u00e9f\u00e9rentiel de toutes les donn\u00e9es importantes que l\u2019on d\u00e9sire sauvegarder.<!--more--><\/p>\n<p>Le <em>Guide d\u2019orientation professionnelle<\/em> pr\u00e9sente \u00e9galement des outils et des ressources pour g\u00e9rer sa carri\u00e8re et prendre des d\u00e9cisions \u00e9clair\u00e9es et efficaces \u00e0 l\u2019\u00e9gard de celle-ci. En plus des \u00e9valuations formatives interactives qui produisent des rapports personnels traitant de toute une panoplie de sujets, on y retrouve des \u00e9valuations allant des points forts et des principaux facteurs de motivation de la personne \u00e0 son aptitude pour diff\u00e9rentes cat\u00e9gories d\u2019emplois. On propose \u00e9galement des conseils pratiques, des strat\u00e9gies et des outils pour permettre l\u2019atteinte de ses objectifs, quels qu\u2019ils soient, ainsi que des conseils adapt\u00e9s \u00e0 sa situation concernant sa carri\u00e8re.<\/p>\n<h4><strong>Que retrouve-t-on dans le <em>Guide d\u2019orientation professionnelle<\/em>?<\/strong><\/h4>\n<h4>Se conna\u00eetre soi-m\u00eame<\/h4>\n<p>Faire des \u00e9valuations interactives et examiner ses rapports personnels, \u00e0 son propre rythme et dans l\u2019ordre de pr\u00e9f\u00e9rence. Se renseigner sur ses valeurs les plus profondes, ses talents uniques et ses pr\u00e9f\u00e9rences en mati\u00e8re de motivation.<\/p>\n<h4>Choisir sa voie<\/h4>\n<p>En d\u00e9couvrir plus au sujet des r\u00f4les, des fonctions et des secteurs qui lui conviennent et des attentes face \u00e0 son employeur. Jeter un coup d\u2019oeil \u00e0 diverses options de carri\u00e8re et d\u00e9velopper un plan d\u2019action.<\/p>\n<h4>Surmonter les troubles de carri\u00e8re<\/h4>\n<p>Apprendre \u00e0 surmonter des difficult\u00e9s de carri\u00e8re telles que l\u2019ennui, l\u2019\u00e9puisement professionnel, un patron difficile, le manque de r\u00e9alisation ou l\u2019\u00e9chec.<\/p>\n<h4>R\u00e9tablir l\u2019\u00e9quilibre<\/h4>\n<p>Avec les obligations et les engagements personnels, identifier ce qui fonctionne et ce qui ne fonctionne pas pour soi. Appliquer des strat\u00e9gies et des conseils pratiques pour ma\u00eetriser sa vie.<\/p>\n<h4>Trouver un emploi id\u00e9al<\/h4>\n<p>Acc\u00e9der \u00e0 des strat\u00e9gies de recherche d\u2019emplois efficaces en \u00e9laborant des outils de valorisation personnelle convaincants tels que le curriculum vitae.<\/p>\n<h4>R\u00e9soudre les dilemmes li\u00e9s aux phases de carri\u00e8re<\/h4>\n<p>Se renseigner sur des strat\u00e9gies sp\u00e9cifiques \u00e0 son \u00e9tape de carri\u00e8re en choisissant celle qui convient le mieux \u00e0 son \u00e2ge afin d\u2019optimiser son potentiel.<\/p>\n<h4>Utiliser les strat\u00e9gies de carri\u00e8re<\/h4>\n<p>Tirer parti des nouvelles r\u00e9alit\u00e9s du travail en se renseignant sur les tendances, les tests et les r\u00e8gles pour obtenir du succ\u00e8s sur les plans professionnel et personnel ainsi que sur les conseils, les tactiques et les autres strat\u00e9gies permettant d\u2019optimiser ses atouts.<\/p>\n<h4>Initier les enfants au monde du travail<\/h4>\n<p>Se renseigner sur des strat\u00e9gies et des ressources pour pr\u00e9parer ses enfants au march\u00e9 du travail.<\/p>\n<h4>Encadrer autrui<\/h4>\n<p>Cadre, mentor ou coach, il s\u2019agit d\u2019acqu\u00e9rir les connaissances et les aptitudes n\u00e9cessaires pour appuyer le perfectionnement d\u2019autrui. P\u00e9n\u00e9trer la mentalit\u00e9 nouvelle des travailleurs et faire appel aux strat\u00e9gies contemporaines gagnantes pour favoriser l\u2019implication.<\/p>\n<p>De par sa multitude de questionnaires, ses ressources et ses pistes de r\u00e9flexion pr\u00e9cieuses, le <em>Guide d\u2019orientation professionnelle<\/em> est un outil diversifi\u00e9 s\u2019adressant notamment aux personnes qui entament une carri\u00e8re, qui envisagent une r\u00e9orientation professionnelle, qui poursuivent un perfectionnement personnel ou qui recherchent de l\u2019avancement. Le fait de pouvoir compl\u00e9ter une section et de la sauvegarder pour une consultation ult\u00e9rieure permet aux utilisateurs de r\u00e9pondre \u00e0 leur rythme et de prendre le temps de r\u00e9flexion n\u00e9cessaire pour bien interpr\u00e9ter leurs r\u00e9sultats. N\u00e9anmoins, cet outil demande un certain niveau de confort avec l\u2019\u00e9criture, la lecture et l\u2019utilisation d\u2019un ordinateur. Un autre crit\u00e8re \u00e0 consid\u00e9rer avant de sugg\u00e9rer cet outil \u00e0 un client serait de v\u00e9rifier s\u2019il est \u00e0 l\u2019aise avec le fait d\u2019entreprendre ce type de r\u00e9flexion par lui-m\u00eame, donc d\u2019avoir une certaine autonomie.<\/p>\n<p>Cet outil n\u2019est pas offert au grand public. Seul les organismes ou les intervenants en gestion de carri\u00e8re peuvent se procurer un acc\u00e8s au <em>Guide d\u2019orientation professionnelle<\/em>. L\u2019achat de 5 acc\u00e8s minimum au co\u00fbt de 250 $ est exig\u00e9. L\u2019intervenant dispose alors d\u2019un d\u00e9lai de 12 mois pour utiliser ses acc\u00e8s. Les prix varient selon le nombre d\u2019acc\u00e8s que l\u2019on d\u00e9sire acheter. Il est aussi important de noter que le mat\u00e9riel promotionnel et explicatif est disponible en anglais seulement. Si vous d\u00e9sirez avoir un avant-go\u00fbt de ce nouvel outil, des acc\u00e8s gratuits pour 48 heures sont offerts. Les personnes int\u00e9ress\u00e9es peuvent communiquer \u00e0 l\u2019adresse suivante pour obtenir de plus amples informations : <a href=\"mailto:aw@bbmcareerdev.com\">aw@bbmcareerdev.com<\/a> ou consulter le site web au <a href=\"http:\/\/www.bbmcareerdev.com\/\" target=\"_blank\" rel=\"noopener\">www.bbmcareerdev.com<\/a>.<\/p>\n<div><\/div>\n<p>Anne-Marie Blanchet est finissante au Baccalaur\u00e9at en sciences de l\u2019orientation de l\u2019Universit\u00e9 Laval. Cet article pour le Bulletin OrientAction a \u00e9t\u00e9 r\u00e9alis\u00e9 dans le cadre de son stage avec l\u2019\u00e9quipe Rep\u00e8res de la Soci\u00e9t\u00e9 GRICS. Courriel: <a href=\"mailto:anne_marie_blanchet@hotmail.com\">anne_marie_blanchet@hotmail.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Anne-Marie Blanchet \u00c9labor\u00e9 \u00e0 partir des principaux concepts d\u00e9velopp\u00e9s par le Dr. Barbara Moses, auteure \u00e0 succ\u00e8s de nombreux ouvrages, le Guide d\u2019orientation professionnelle constitue<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[565,542,29,729],"tags":[],"class_list":["post-28783","post","type-post","status-publish","format-standard","hentry","category-ete-2006","category-le-bulletin","category-non-classifiee","category-s06-fr-article-de-fond"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle - CERIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle\" \/>\n<meta property=\"og:description\" content=\"par Anne-Marie Blanchet \u00c9labor\u00e9 \u00e0 partir des principaux concepts d\u00e9velopp\u00e9s par le Dr. Barbara Moses, auteure \u00e0 succ\u00e8s de nombreux ouvrages, le Guide d\u2019orientation professionnelle constitue [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/\" \/>\n<meta property=\"og:site_name\" content=\"CERIC\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-06T21:45:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-26T20:38:25+00:00\" \/>\n<meta name=\"author\" content=\"Norman Valdez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rachel@ceric.ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norman Valdez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/\"},\"author\":{\"name\":\"Norman Valdez\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\"},\"headline\":\"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle\",\"datePublished\":\"2012-11-06T21:45:52+00:00\",\"dateModified\":\"2018-06-26T20:38:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/\"},\"wordCount\":1048,\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"articleSection\":[\"\u00c9t\u00e9 2006\",\"Le Bulletin\",\"Non classifi\u00e9(e)\",\"S06 \u2013 FR \u2013 Article de fond\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/\",\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/\",\"name\":\"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle - CERIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\"},\"datePublished\":\"2012-11-06T21:45:52+00:00\",\"dateModified\":\"2018-06-26T20:38:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2012\\\/11\\\/notre-avis-sur-loutil-guide-dorientation-professionnelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/ceric-homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"name\":\"CERIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceric.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\",\"name\":\"CERIC\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CERIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/444d77ede5f23ae98c74e54ab17e2da2\",\"name\":\"Norman Valdez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g\",\"caption\":\"Norman Valdez\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/rachel@ceric.ca\"],\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/author\\\/norman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle - CERIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle","og_description":"par Anne-Marie Blanchet \u00c9labor\u00e9 \u00e0 partir des principaux concepts d\u00e9velopp\u00e9s par le Dr. Barbara Moses, auteure \u00e0 succ\u00e8s de nombreux ouvrages, le Guide d\u2019orientation professionnelle constitue [\u2026]","og_url":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/","og_site_name":"CERIC","article_published_time":"2012-11-06T21:45:52+00:00","article_modified_time":"2018-06-26T20:38:25+00:00","author":"Norman Valdez","twitter_card":"summary_large_image","twitter_creator":"@rachel@ceric.ca","twitter_misc":{"\u00c9crit par":"Norman Valdez","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/#article","isPartOf":{"@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/"},"author":{"name":"Norman Valdez","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2"},"headline":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle","datePublished":"2012-11-06T21:45:52+00:00","dateModified":"2018-06-26T20:38:25+00:00","mainEntityOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/"},"wordCount":1048,"publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"articleSection":["\u00c9t\u00e9 2006","Le Bulletin","Non classifi\u00e9(e)","S06 \u2013 FR \u2013 Article de fond"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/","url":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/","name":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle - CERIC","isPartOf":{"@id":"https:\/\/ceric.ca\/#website"},"datePublished":"2012-11-06T21:45:52+00:00","dateModified":"2018-06-26T20:38:25+00:00","breadcrumb":{"@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ceric.ca\/fr\/2012\/11\/notre-avis-sur-loutil-guide-dorientation-professionnelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceric.ca\/fr\/ceric-homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Notre avis sur l\u2019outil : Guide d\u2019orientation professionnelle"}]},{"@type":"WebSite","@id":"https:\/\/ceric.ca\/#website","url":"https:\/\/ceric.ca\/","name":"CERIC","description":"","publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceric.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ceric.ca\/#organization","name":"CERIC","url":"https:\/\/ceric.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CERIC"},"image":{"@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ceric.ca\/#\/schema\/person\/444d77ede5f23ae98c74e54ab17e2da2","name":"Norman Valdez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/01def366a03d176e612e177e52d2c8b99d80f13e922b93d5fb9696239fb7fbd4?s=96&d=blank&r=g","caption":"Norman Valdez"},"sameAs":["https:\/\/x.com\/rachel@ceric.ca"],"url":"https:\/\/ceric.ca\/fr\/author\/norman\/"}]}},"_links":{"self":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/28783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/comments?post=28783"}],"version-history":[{"count":0,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/28783\/revisions"}],"wp:attachment":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media?parent=28783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/categories?post=28783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/tags?post=28783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}