{"id":36336,"date":"2020-01-21T11:33:48","date_gmt":"2020-01-21T16:33:48","guid":{"rendered":"https:\/\/ceric.ca\/?p=36336"},"modified":"2020-04-23T14:40:20","modified_gmt":"2020-04-23T18:40:20","slug":"revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte","status":"publish","type":"post","link":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/","title":{"rendered":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte"},"content":{"rendered":"<p>En r\u00e9ponse \u00e0 la forte demande pour des dipl\u00f4m\u00e9s en informatique au Canada et au paysage technologique en pleine transformation, le CERIC a publi\u00e9 une version mise \u00e0 jour de son guide des carri\u00e8res en informatique. R\u00e9dig\u00e9e par Randy\u00a0Connolly, Janet\u00a0Miller et Faith-Michael\u00a0Uzoka de l\u2019<a href=\"https:\/\/www.mtroyal.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Universit\u00e9\u00a0Mount\u00a0Royal<\/a>, la deuxi\u00e8me \u00e9dition du guide intitul\u00e9 <a href=\"http:\/\/www.ceric.ca\/computing\"><em>Computing Careers &amp; Disciplines: A Quick Guide for Prospective Students and Career Advisors<\/em><\/a> fournit les plus r\u00e9cents renseignements sur les types de carri\u00e8res en informatique et les \u00e9tudes n\u00e9cessaires pour y arriver. Vous pouvez d\u00e8s maintenant t\u00e9l\u00e9charger gratuitement le nouveau guide qui sera lanc\u00e9 lors du <a href=\"http:\/\/www.cannexus.ca\/\">Congr\u00e8s national en d\u00e9veloppement de carri\u00e8re\u00a0Cannexus<\/a> qui se d\u00e9roulera \u00e0 Ottawa la semaine prochaine.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-36233 size-medium\" src=\"https:\/\/ceric.ca\/wp-content\/uploads\/2017\/11\/Computing-Discipline-2.0-276x300.png\" alt=\"Computing Careers and Disciplines\" width=\"276\" height=\"300\" srcset=\"https:\/\/ceric.ca\/wp-content\/uploads\/2017\/11\/Computing-Discipline-2.0-276x300.png 276w, https:\/\/ceric.ca\/wp-content\/uploads\/2017\/11\/Computing-Discipline-2.0.png 450w\" sizes=\"(max-width:767px) 276px, 276px\" \/>Le nouveau guide d\u00e9crit les cinq principales disciplines informatiques d\u00e9finies par l\u2019<a href=\"https:\/\/www.acm.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Association for Computing Machinery (ACM)<\/a> et pr\u00e9sente six autres sp\u00e9cialisations populaires en informatique. Ces descriptions visent \u00e0 aider les futurs \u00e9tudiants, parents, conseillers p\u00e9dagogiques et conseillers d\u2019orientation \u00e0 naviguer dans le labyrinthe de disciplines informatiques et d\u2019options d\u2019\u00e9tudes postsecondaires. Pour chacune des principales disciplines, le guide fait le survol des t\u00e2ches li\u00e9es aux emplois et indique les cours de base, des exemples de dipl\u00f4mes et d\u2019autres cheminements au sein d\u2019universit\u00e9s et de coll\u00e8ges canadiens.<\/p>\n<p>Le guide, color\u00e9 et rempli de tableaux, d\u00e9veloppe le contenu de la populaire premi\u00e8re \u00e9dition de\u00a02017 pour r\u00e9pondre \u00e0 ces trois questions.<\/p>\n<ul>\n<li>Pourquoi choisir une carri\u00e8re en informatique?<\/li>\n<li>Quels types d\u2019emplois existe-t-il en informatique?<\/li>\n<li>Quels types de parcours d\u2019\u00e9tudes vous m\u00e8neront vers la carri\u00e8re en informatique que vous d\u00e9sirez?<\/li>\n<\/ul>\n<p>Le guide s\u2019inspire des conclusions d\u2019un <a href=\"https:\/\/ceric.ca\/project\/investigating-students-knowledge-of-the-computing-sub-disciplines-recommendations-for-career-counsellors-and-curriculum-developers\/\">projet de recherche international financ\u00e9 par le\u00a0CERIC<\/a> qui a sond\u00e9 des milliers d\u2019\u00e9tudiants et de membres du corps professoral du Canada, des \u00c9tats-Unis et d\u2019Afrique. La recherche a r\u00e9v\u00e9l\u00e9 que la plupart des \u00e9tudiants de premier cycle ne comprenaient pas la diff\u00e9rence entre les diverses disciplines informatiques. Le guide a aussi \u00e9t\u00e9 cr\u00e9\u00e9 en r\u00e9ponse au besoin des conseillers en d\u00e9veloppement de carri\u00e8re qui orientent les \u00e9tudiants des niveaux secondaire et postsecondaire qui s\u2019int\u00e9ressent \u00e0 la technologie. Il aide les \u00e9tudiants \u00e0 prendre des d\u00e9cisions sur leurs \u00e9tudes en informatique et leurs cheminements de carri\u00e8re qui correspondent \u00e0 leurs valeurs, \u00e0 leurs int\u00e9r\u00eats et \u00e0 leurs habilet\u00e9s. Tout particuli\u00e8rement, le guide fait conna\u00eetre les disciplines aux \u00e9tudiants avant leur demande d\u2019admission \u00e0 un programme ou le choix de leur majeure.<\/p>\n<p>La version mise \u00e0 jour cherche \u00e0 dissiper les mythes entourant les carri\u00e8res en informatique. Contrairement aux st\u00e9r\u00e9otypes v\u00e9hicul\u00e9s, l\u2019informatique est souvent une activit\u00e9 hautement sociale. Ce domaine favorise un mode de vie souple, la cr\u00e9ativit\u00e9 et le travail \u00e0 l\u2019\u00e9tranger. Le guide souligne \u00e9galement que le travail informatique est tr\u00e8s vari\u00e9 et ne se limite pas \u00e0 la programmation.<\/p>\n<p>Les cinq disciplines de l\u2019informatique d\u00e9crites dans le guide sont les suivantes\u00a0:<\/p>\n<ul>\n<li>G\u00e9nie informatique\u00a0\u2013 conception et architecture d\u2019ordinateurs et de syst\u00e8mes informatis\u00e9s<\/li>\n<li>Science informatique\u00a0\u2013 \u00e9tude exhaustive du domaine de l\u2019informatique, des fondements th\u00e9oriques aux derniers d\u00e9veloppements techniques<\/li>\n<li>Technologie de l\u2019information\u00a0\u2013 application de la technologie informatique aux besoins des entreprises et des autres organisations<\/li>\n<li>Syst\u00e8mes d\u2019information\u00a0\u2013 int\u00e9gration de la technologie de l\u2019information dans les proc\u00e9d\u00e9s op\u00e9rationnels<\/li>\n<li>G\u00e9nie logiciel\u00a0\u2013 conception et tenue \u00e0 jour de gros syst\u00e8mes logiciels<\/li>\n<\/ul>\n<p>Sp\u00e9cialisations\u00a0: technologie r\u00e9seau, science des donn\u00e9es, bio-informatique, d\u00e9veloppement de jeux, multim\u00e9dia, d\u00e9veloppement\u00a0Web et cybers\u00e9curit\u00e9.<\/p>\n<p>Le guide souligne que de nombreux chemins m\u00e8nent vers la plupart des carri\u00e8res en informatique. Cela comprend des dipl\u00f4mes de trois et quatre ans, des dipl\u00f4mes de deux ans et des certificats d\u2019un an, en plus de programmes de formation autonomes ou de sp\u00e9cialisations postdipl\u00f4me. Il peut \u00eatre difficile de s\u2019y retrouver, car les titres de programmes ne correspondent pas toujours aux cinq disciplines ni \u00e0 des titres de poste sur le march\u00e9 du travail.<\/p>\n<p>La nouvelle \u00e9dition du guide comprend aussi des profils de dipl\u00f4m\u00e9s et des ressources additionnelles. Vous trouverez aussi plus de contenu sur un site Web associ\u00e9\u00a0: <a href=\"http:\/\/www.computingcareers.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">computingcareers.ca<\/a>. Une r\u00e9vision de la <a href=\"https:\/\/ceric.ca\/fr\/resource\/les-disciplines-informatiques-petit-guide-lintention-des-futurs-etudiants-et-des-conseillers-dorientation\/\">version\u00a0fran\u00e7aise<\/a> du guide est en cours et devrait \u00eatre pr\u00eate au printemps.<\/p>\n<p>En plus de t\u00e9l\u00e9charger le nouveau guide gratuitement sur le site\u00a0Web du CERIC \u00e0 l\u2019adresse <a href=\"http:\/\/www.ceric.ca\/computing\">ceric.ca\/computing<\/a>, vous pouvez \u00e9galement en commander des exemplaires imprim\u00e9s aupr\u00e8s du CERIC, au prix de 10\u00a0$ l\u2019exemplaire pour les commandes par lot de 10\u00a0ou plus. Vous pourrez vous procurer des exemplaires \u00e0 l\u2019unit\u00e9 uniquement lors du congr\u00e8s Cannexus. \u00c9crivez \u00e0 <a href=\"mailto:sales@ceric.ca\">sales@ceric.ca<\/a> pour en savoir plus.<\/p>\n<p>Le lundi 27\u00a0janvier, les auteurs du guide feront une pr\u00e9sentation sur les <a href=\"https:\/\/sched.co\/V3X8\" target=\"_blank\" rel=\"noopener noreferrer\">disciplines informatiques\u00a02.0\u00a0: ce que doivent savoir les conseillers en d\u00e9veloppement de carri\u00e8re<\/a> \u00e0 l\u2019occasion du congr\u00e8s Cannexus20.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En r\u00e9ponse \u00e0 la forte demande pour des dipl\u00f4m\u00e9s en informatique au Canada et au paysage technologique en pleine transformation, le CERIC a publi\u00e9 une version<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":30,"featured_media":36264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[861,862,32],"tags":[],"class_list":["post-36336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2020-nouvelles","category-janvier-2020-nouvelles","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC\" \/>\n<meta property=\"og:description\" content=\"En r\u00e9ponse \u00e0 la forte demande pour des dipl\u00f4m\u00e9s en informatique au Canada et au paysage technologique en pleine transformation, le CERIC a publi\u00e9 une version [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/\" \/>\n<meta property=\"og:site_name\" content=\"CERIC\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T16:33:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-23T18:40:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rachel So\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel So\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/\"},\"author\":{\"name\":\"Rachel So\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/2e3faddf54acfac0d88b9ce185094d00\"},\"headline\":\"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte\",\"datePublished\":\"2020-01-21T16:33:48+00:00\",\"dateModified\":\"2020-04-23T18:40:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/\"},\"wordCount\":876,\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/computing-1.png\",\"articleSection\":[\"2020\",\"janvier\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/\",\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/\",\"name\":\"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/computing-1.png\",\"datePublished\":\"2020-01-21T16:33:48+00:00\",\"dateModified\":\"2020-04-23T18:40:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/computing-1.png\",\"contentUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/computing-1.png\",\"width\":600,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2020\\\/01\\\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/ceric-homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"name\":\"CERIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceric.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\",\"name\":\"CERIC\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CERIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/2e3faddf54acfac0d88b9ce185094d00\",\"name\":\"Rachel So\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"caption\":\"Rachel So\"},\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/author\\\/rachel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC","og_description":"En r\u00e9ponse \u00e0 la forte demande pour des dipl\u00f4m\u00e9s en informatique au Canada et au paysage technologique en pleine transformation, le CERIC a publi\u00e9 une version [\u2026]","og_url":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/","og_site_name":"CERIC","article_published_time":"2020-01-21T16:33:48+00:00","article_modified_time":"2020-04-23T18:40:20+00:00","og_image":[{"width":600,"height":430,"url":"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png","type":"image\/png"}],"author":"Rachel So","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rachel So","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#article","isPartOf":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/"},"author":{"name":"Rachel So","@id":"https:\/\/ceric.ca\/#\/schema\/person\/2e3faddf54acfac0d88b9ce185094d00"},"headline":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte","datePublished":"2020-01-21T16:33:48+00:00","dateModified":"2020-04-23T18:40:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/"},"wordCount":876,"publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"image":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#primaryimage"},"thumbnailUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png","articleSection":["2020","janvier","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/","url":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/","name":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte - CERIC","isPartOf":{"@id":"https:\/\/ceric.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#primaryimage"},"image":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#primaryimage"},"thumbnailUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png","datePublished":"2020-01-21T16:33:48+00:00","dateModified":"2020-04-23T18:40:20+00:00","breadcrumb":{"@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#primaryimage","url":"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png","contentUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2020\/01\/computing-1.png","width":600,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/ceric.ca\/fr\/2020\/01\/revision-pour-2020-une-nouvelle-edition-du-guide-des-carrieres-en-informatique-a-lintention-des-etudiants-et-des-conseillers-est-maintenant-offerte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceric.ca\/fr\/ceric-homepage-2025\/"},{"@type":"ListItem","position":2,"name":"R\u00e9vision pour 2020 : Une nouvelle \u00e9dition du guide des carri\u00e8res en informatique \u00e0 l\u2019intention des \u00e9tudiants et des conseillers est maintenant offerte"}]},{"@type":"WebSite","@id":"https:\/\/ceric.ca\/#website","url":"https:\/\/ceric.ca\/","name":"CERIC","description":"","publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceric.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ceric.ca\/#organization","name":"CERIC","url":"https:\/\/ceric.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CERIC"},"image":{"@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ceric.ca\/#\/schema\/person\/2e3faddf54acfac0d88b9ce185094d00","name":"Rachel So","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","caption":"Rachel So"},"url":"https:\/\/ceric.ca\/fr\/author\/rachel\/"}]}},"_links":{"self":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/36336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/comments?post=36336"}],"version-history":[{"count":0,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/36336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media\/36264"}],"wp:attachment":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media?parent=36336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/categories?post=36336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/tags?post=36336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}