{"id":63799,"date":"2024-01-29T05:30:52","date_gmt":"2024-01-29T10:30:52","guid":{"rendered":"https:\/\/ceric.ca\/?p=63799"},"modified":"2024-01-28T22:44:46","modified_gmt":"2024-01-29T03:44:46","slug":"le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere","status":"publish","type":"post","link":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/","title":{"rendered":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re"},"content":{"rendered":"<p><strong>Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re<\/strong><\/p>\n<p>Une nouvelle version de la <a href=\"https:\/\/ceric.ca\/fr\/la-base-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/\">base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re<\/a> du CERIC est maintenant disponible, r\u00e9pondant ainsi \u00e0 la question : \u00ab\u00a0Qui fait quelle recherche au Canada?\u00a0\u00bb Le Canada regorge de chercheurs \u00e9minents, dans les milieux universitaires ou communautaires partout au pays, qui accomplissent un travail important dans de nombreux domaines li\u00e9s au d\u00e9veloppement de carri\u00e8re. La base de donn\u00e9es r\u00e9unit ces renseignements pr\u00e9cieux \u00e0 partir d\u2019un outil de recherche en ligne facile \u00e0 utiliser.<\/p>\n<p>La base de donn\u00e9es compte actuellement 201\u00a0chercheurs, anglophones et francophones. Il est pr\u00e9vu que la base de donn\u00e9es soit mise \u00e0 jour en permanence et que de nouveaux chercheurs y soient ajout\u00e9s. La base de donn\u00e9es peut \u00eatre filtr\u00e9e par institution, par lieu ou par plus de 50\u00a0domaines d\u2019int\u00e9r\u00eat, du genre de la personne \u00e0 la psychologie professionnelle, et du d\u00e9veloppement de carri\u00e8re chez les autochtones \u00e0 la justice sociale.<\/p>\n<p><strong>Quelle est l\u2019utilit\u00e9 de la base de donn\u00e9es?<\/strong><\/p>\n<ul>\n<li>Les chercheurs, les \u00e9tudiants, les organisations et la population en g\u00e9n\u00e9ral peuvent utiliser la base de donn\u00e9es pour d\u00e9terminer les partenaires universitaires et non universitaires pour de prochains projets de recherche.<\/li>\n<li>On peut \u00e9galement l\u2019utiliser pour prendre connaissance de la recherche actuellement effectu\u00e9e au Canada et se renseigner sur la meilleure fa\u00e7on de faire progresser ces connaissances.<\/li>\n<li>La base de donn\u00e9es est \u00e9galement pr\u00e9cieuse en tant que point de d\u00e9part pour les personnes qui veulent se renseigner sur les derni\u00e8res recherches dans le domaine du d\u00e9veloppement de carri\u00e8re.<\/li>\n<\/ul>\n<p>Le tout commence par Michael\u00a0<strong><u>Abbott<\/u><\/strong> de l\u2019Universit\u00e9 Queen\u2019s en Ontario, qui s\u2019int\u00e9resse aux march\u00e9s du travail, en passant par Marcelline\u00a0<strong><u>B<\/u>engaly<\/strong> de l\u2019Universit\u00e9 Laval au Qu\u00e9bec, dont les recherches portent sur les groupes d\u2019immigrants, et Dave\u00a0<strong><u>R<\/u>edekopp<\/strong> du Life-Role Development Group en Alberta, qui s\u2019int\u00e9resse \u00e0 la sant\u00e9 mentale, pour se terminer par Richard\u00a0<strong><u>Y<\/u>oung<\/strong> en Colombie-Britannique, qui a fait des recherches sur les jeunes et les transitions. Vous \u00eates invit\u00e9s \u00e0 parcourir la base de donn\u00e9es qui se trouve \u00e0 l\u2019adresse <a href=\"https:\/\/ceric.ca\/fr\/la-base-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/\">ceric.ca\/chercheurs<\/a><\/p>\n<p>Conform\u00e9ment aux priorit\u00e9s strat\u00e9giques du CERIC, nous sommes convaincus qu\u2019en soutenant les chercheurs \u00e0 l\u2019aide d\u2019une documentation ad\u00e9quate, nous pouvons continuer de faire avancer les connaissances th\u00e9oriques et pratiques en d\u00e9veloppement de carri\u00e8re, encourager la collaboration entre divers intervenants et faciliter les interactions entre<\/p>\n<p>En particulier, toute personne <a href=\"https:\/\/ceric.ca\/fr\/partenariats\/\">sollicitant le CERIC pour le financement d\u2019un projet<\/a> trouvera comment proc\u00e9der pour tirer parti de la recherche existante, et s\u2019il existe des possibilit\u00e9s de collaboration. Parmi les autres ressources connexes, on retrouve\u00a0: <a href=\"https:\/\/ceric.ca\/fr\/listes-de-documents\/\">60\u00a0recherches documentaires du CERIC<\/a>, la <a href=\"https:\/\/cjcd-rcdc.ceric.ca\/index.php\/cjcd\" target=\"_blank\" rel=\"noopener\"><em>Revue canadienne de d\u00e9veloppement de carri\u00e8re<\/em><\/a> ainsi que notre liste de <a href=\"https:\/\/ceric.ca\/fr\/projets\/\">projets pr\u00e9c\u00e9demment financ\u00e9s<\/a>.<\/p>\n<p>Le CERIC s\u2019efforcera de maintenir la base de donn\u00e9es aussi \u00e0 jour et pr\u00e9cise que possible. Les chercheurs sont invit\u00e9s \u00e0 communiquer avec nous pour \u00eatre ajout\u00e9s \u00e0 la base de donn\u00e9es ou pour faire modifier leurs informations. Toute personne est \u00e9galement invit\u00e9e \u00e0 recommander un chercheur canadien \u00e0 ajouter \u00e0 la liste en envoyant un courriel \u00e0 Alexandra\u00a0Manoliu, responsable des initiatives de recherche au CERIC, \u00e0 l\u2019adresse <a href=\"mailto:alexandra@ceric.ca\">alexandra@ceric.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re Une nouvelle version de la base de donn\u00e9es des chercheurs canadiens en<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":30,"featured_media":63796,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","h5ap_radio_sources":[],"page_builder":"","footnotes":""},"categories":[1194,1195,32],"tags":[],"class_list":["post-63799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2024-nouvelles","category-janvier-2024-nouvelles","category-nouvelles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re - CERIC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re\" \/>\n<meta property=\"og:description\" content=\"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re Une nouvelle version de la base de donn\u00e9es des chercheurs canadiens en [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/\" \/>\n<meta property=\"og:site_name\" content=\"CERIC\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-29T10:30:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Rachel So\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel So\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/\"},\"author\":{\"name\":\"Rachel So\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/2e3faddf54acfac0d88b9ce185094d00\"},\"headline\":\"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re\",\"datePublished\":\"2024-01-29T10:30:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Researcher-Database-ft-image.png\",\"articleSection\":[\"2024\",\"janvier\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/\",\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/\",\"name\":\"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re - CERIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Researcher-Database-ft-image.png\",\"datePublished\":\"2024-01-29T10:30:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Researcher-Database-ft-image.png\",\"contentUrl\":\"https:\\\/\\\/ceric.ca\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Researcher-Database-ft-image.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/2024\\\/01\\\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/ceric-homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#website\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"name\":\"CERIC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ceric.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#organization\",\"name\":\"CERIC\",\"url\":\"https:\\\/\\\/ceric.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CERIC\"},\"image\":{\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ceric.ca\\\/#\\\/schema\\\/person\\\/2e3faddf54acfac0d88b9ce185094d00\",\"name\":\"Rachel So\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g\",\"caption\":\"Rachel So\"},\"url\":\"https:\\\/\\\/ceric.ca\\\/fr\\\/author\\\/rachel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re - CERIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/","og_locale":"fr_FR","og_type":"article","og_title":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re","og_description":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re Une nouvelle version de la base de donn\u00e9es des chercheurs canadiens en [\u2026]","og_url":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/","og_site_name":"CERIC","article_published_time":"2024-01-29T10:30:52+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png","type":"image\/png"}],"author":"Rachel So","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rachel So","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#article","isPartOf":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/"},"author":{"name":"Rachel So","@id":"https:\/\/ceric.ca\/#\/schema\/person\/2e3faddf54acfac0d88b9ce185094d00"},"headline":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re","datePublished":"2024-01-29T10:30:52+00:00","mainEntityOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/"},"wordCount":595,"publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"image":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#primaryimage"},"thumbnailUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png","articleSection":["2024","janvier","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/","url":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/","name":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re - CERIC","isPartOf":{"@id":"https:\/\/ceric.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#primaryimage"},"image":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#primaryimage"},"thumbnailUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png","datePublished":"2024-01-29T10:30:52+00:00","breadcrumb":{"@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#primaryimage","url":"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png","contentUrl":"https:\/\/ceric.ca\/wp-content\/uploads\/2024\/01\/Researcher-Database-ft-image.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ceric.ca\/fr\/2024\/01\/le-ceric-relance-la-base-de-donnees-des-chercheurs-canadiens-en-developpement-de-carriere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ceric.ca\/fr\/ceric-homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Le CERIC relance la base de donn\u00e9es des chercheurs canadiens en d\u00e9veloppement de carri\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/ceric.ca\/#website","url":"https:\/\/ceric.ca\/","name":"CERIC","description":"","publisher":{"@id":"https:\/\/ceric.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ceric.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ceric.ca\/#organization","name":"CERIC","url":"https:\/\/ceric.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CERIC"},"image":{"@id":"https:\/\/ceric.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ceric.ca\/#\/schema\/person\/2e3faddf54acfac0d88b9ce185094d00","name":"Rachel So","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c40c9aaacb6f176dbd977bdf43366708b68bdf16dc927d1e222e96783b5a9bc?s=96&d=blank&r=g","caption":"Rachel So"},"url":"https:\/\/ceric.ca\/fr\/author\/rachel\/"}]}},"_links":{"self":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/63799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/comments?post=63799"}],"version-history":[{"count":0,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/posts\/63799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media\/63796"}],"wp:attachment":[{"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/media?parent=63799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/categories?post=63799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ceric.ca\/fr\/wp-json\/wp\/v2\/tags?post=63799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}